{"id":23822,"date":"2022-05-25T17:40:15","date_gmt":"2022-05-25T15:40:15","guid":{"rendered":"https:\/\/circutor.com\/non-classifiee\/la-proteccion-diferencial-en-los-variadores-de-velocidad\/"},"modified":"2022-06-09T13:13:44","modified_gmt":"2022-06-09T11:13:44","slug":"la-protection-differentielle-dans-les-variateurs-de-vitesse","status":"publish","type":"post","link":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/","title":{"rendered":"La protection diff\u00e9rentielle dans les variateurs de vitesse"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]L&rsquo;utilisation d&rsquo;un ou de plusieurs variateurs de vitesse est de plus en plus r\u00e9pandue dans de nombreux proc\u00e9d\u00e9s industriels\u00a0: des applications de base comme le pompage, aux machines pr\u00e9cises avec des op\u00e9rations robotis\u00e9es. Mais nous les utilisons aussi tous les jours\u00a0: elle est int\u00e9gr\u00e9e dans les lave-linge, les ascenseurs et les syst\u00e8mes modernes de climatisation.<\/p>\n<p>[vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb][\/vc_column_text][vc_single_image image=\u00a0\u00bb21894&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb][vc_column_text]<\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #426da8;\">Une protection diff\u00e9rentielle de type B doit \u00eatre install\u00e9e dans toute installation avec pr\u00e9sence de variateurs\u00a0; industrie, cha\u00eenes de montage, chariots \u00e9l\u00e9vateurs, etc.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb]<\/p>\n<p>Le variateur est une charge un peu particuli\u00e8re qui doit \u00eatre prise en consid\u00e9ration lors du choix de sa protection diff\u00e9rentielle correcte, notamment dans les processus et applications dont la continuit\u00e9 de service est essentielle. <strong>Une mauvaise conception ou une mauvaise ing\u00e9nierie dans le choix de la protection diff\u00e9rentielle dans ces variateurs peut d\u00e9boucher sur des d\u00e9clenchements intempestifs qui vont g\u00eaner notre processus de production<\/strong>. Sans parler du co\u00fbt direct que l&rsquo;arr\u00eat et le d\u00e9marrage ult\u00e9rieur entra\u00eeneraient.[\/vc_column_text][vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb]<\/p>\n<h3>Comment choisir la protection diff\u00e9rentielle?<\/h3>\n<p>Nous devons rechercher certaines des cl\u00e9s pour comprendre quelle protection diff\u00e9rentielle vous devez choisir pour votre variateur dans deux des particularit\u00e9s de son fonctionnement:<\/p>\n<p><strong>1-<\/strong> Les filtres EMI qui utilisent couramment les variateurs (qui att\u00e9nuent les fr\u00e9quences de commutation du variateur lui-m\u00eame dans son fonctionnement)<\/p>\n<p><strong>2- <\/strong>Que leur utilisation perturbe notre r\u00e9seau \u00e9lectrique avec pr\u00e9sence d&rsquo;harmoniques.<\/p>\n<p><strong>En quoi le filtre EMI affecte-t-il la protection diff\u00e9rentielle\u00a0?<\/strong><\/p>\n<p>Il est important de savoir que tous les filtres EMI se comportent comme un condensateur \u00e0 terre et que leur utilisation fait donc circuler un courant \u00e0 terre qui est mesur\u00e9 par tout diff\u00e9rentiel comme une fuite. Si ce courant \u00e0 la terre entre dans le seuil de d\u00e9clenchement du diff\u00e9rentiel, celui-ci pourrait sauter.<\/p>\n<p>Conform\u00e9ment \u00e0 la norme CEI-60947-2-M, un diff\u00e9rentiel doit se d\u00e9clencher avec un courant compris entre 50 et 100\u00a0% de sa sensibilit\u00e9. Prenons des nombres pour mieux comprendre ce concept\u00a0: si votre diff\u00e9rentiel a une sensibilit\u00e9 de 300 mA, cela signifie qu&rsquo;il doit se d\u00e9clencher quand il mesure une fuite d&rsquo;entre 150 (50\u00a0%) et 300 mA (100\u00a0%).<\/p>\n<p><span style=\"color: #426da8;\">\u00c0 titre d&rsquo;exemple, si l&rsquo;on tient compte d&rsquo;un courant de fuite maximal typique pour les variateurs triphas\u00e9s d&rsquo;environ 1 kW de 10 mA (les donn\u00e9es exactes de votre variateur peuvent \u00eatre extraites de la fiche technique du filtre EMI), nous vous recommandons d&rsquo;installer un maximum de 12 convertisseurs par diff\u00e9rentiel. Remarquez que 12 x 10 mA = 120 mA, est une valeur loin encore des 150 mA \u00e0 partir desquels il peut se d\u00e9clencher. Ainsi, vous \u00e9viterez les d\u00e9clenchements intempestifs importuns dans votre protection diff\u00e9rentielle.<\/span><\/p>\n<p>La deuxi\u00e8me particularit\u00e9 que nous devons prendre en consid\u00e9ration pour le choix du diff\u00e9rentiel, si nous voulons obtenir une protection correcte des variateurs, est que leur utilisation perturbe le r\u00e9seau \u00e9lectrique avec des harmoniques. <strong>Le probl\u00e8me ici est que certains types de diff\u00e9rentiel, n&rsquo;\u00e9tant pas pr\u00e9par\u00e9s pour ces fr\u00e9quences harmoniques, peuvent induire de nouveaux d\u00e9clenchements intempestifs.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][vc_empty_space height=\u00a0\u00bb40px\u00a0\u00bb]<\/p>\n<h3>L&rsquo;offre de CIRCUTOR<\/h3>\n<p>CIRCUTOR, qui a accumul\u00e9 une vaste exp\u00e9rience dans la conception de solutions de protection diff\u00e9rentielle depuis ses origines, en 1973, int\u00e8gre dans ses syst\u00e8mes de protection de type A un syst\u00e8me d&rsquo;ultra-immunit\u00e9, qui offre une s\u00e9rie d&rsquo;avantages sp\u00e9cifiquement con\u00e7us pour ce champ d&rsquo;application.<\/p>\n<p>En particulier, toute la <strong>protection diff\u00e9rentielle de CIRCUTOR garantit le d\u00e9clenchement \u00e0 partir de 85\u00a0% de sa sensibilit\u00e9, d\u00e9passant les 50\u00a0% requis par la norme<\/strong>. Ainsi, nous fixons le d\u00e9clenchement au sommet du seuil, ce qui signifie en pratique que nous pouvons mettre une charge suppl\u00e9mentaire. Ou bien nous avons un plus grand \u00ab\u00a0matelas\u00a0\u00bb de s\u00e9curit\u00e9 avant un d\u00e9clenchement. <strong>En bref\u00a0: C&rsquo;est une caract\u00e9ristique tr\u00e8s utile qui vous aide \u00e0 \u00e9viter des d\u00e9clenchements dans votre protection.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb]<\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #426da8;\">Certains de nos \u00e9quipements de protection diff\u00e9rentielle avec <strong>syst\u00e8me ultra-immunis\u00e9<\/strong><\/span><\/p>\n<p>[vc_empty_space height=\u00a0\u00bb10px\u00a0\u00bb][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb22041&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/circutor.com\/fr\/produits\/protection-et-controle\/protection-differentielle\/protection-differentielle-type-a\/product\/P11941.\/\u00a0\u00bb][vc_column_text]<strong>RGU-10<\/strong>,\u00a0Relais diff\u00e9rentiel pour transformateur WGC, type A, 3 modules et affichage<\/p>\n<p>[vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb][\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb22060&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/circutor.com\/fr\/produits\/protection-differentielle\/protection-differentielle-type-a\/relais-differentiel-pour-transformateur-wgc-type-a-ultra-immunise-2-modules-avec-ecran-et-sortie-pre-alarme-programmable-fixe.\/product\/P11A61.\/\u00a0\u00bb][vc_column_text]<strong>RGU-2<\/strong>, Relais diff\u00e9rentiels pour transformateur WGC, type A, 2 modules et affichage<\/p>\n<p>[vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb21946&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/circutor.com\/fr\/produits\/protection-et-controle\/protection-differentielle\/protection-differentielle-type-a\/product\/P12A32.\/\u00a0\u00bb][vc_column_text]<strong>RGE-RL<\/strong>, Relais diff\u00e9rentiel pour transformateur WGC, type A ultra-immunis\u00e9<\/p>\n<p>[vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb][\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb21977&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/circutor.com\/fr\/produits\/protection-et-controle\/protection-differentielle\/protection-differentielle-type-a\/product\/P14035.\/\u00a0\u00bb][vc_column_text]<strong>WRU-10<\/strong>, Relais diff\u00e9rentiel de type A ultra-immunis\u00e9 avec transformateur int\u00e9gr\u00e9<\/p>\n<p>[vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb21970&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/circutor.com\/fr\/produits\/protection-et-controle\/protection-differentielle\/protection-differentielle-type-a\/serie\/wgc\/\u00a0\u00bb][vc_column_text]<strong>WGC, <\/strong>Transformateur diff\u00e9rentiel[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb]<\/p>\n<p>Un autre avantage du syst\u00e8me ultra-immunis\u00e9 de CIRCUTOR <strong>est l&rsquo;immunit\u00e9 qu&rsquo;il offre face \u00e0 la pr\u00e9sence d&rsquo;harmoniques<\/strong>, en traitant le courant mesur\u00e9 et en \u00e9liminant ou en filtrant les fr\u00e9quences sup\u00e9rieures \u00e0 50\/60\u00a0Hz. Il s&rsquo;agit, avec l&rsquo;immunit\u00e9 transitoire, d&rsquo;une bonne prestation qui \u00e9limine les d\u00e9clenchements provoqu\u00e9s par ce type de perturbations dans les installations.<\/p>\n<p>[vc_empty_space height=\u00a0\u00bb30px\u00a0\u00bb][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_raw_html]JTNDaSUyMGNsYXNzJTNEJTIyaWNvLXNjYWRhLXNjcmVlbiUyMiUyMHN0eWxlJTNEJTIyZm9udC1zaXplJTNBMnJlbSUzQiUyMiUzRSUzQyUyRmklM0U=[\/vc_raw_html][vc_column_text]<strong>Marge de d\u00e9clenchement entre 85\u00a0% et 100\u00a0% de la sensibilit\u00e9.<\/strong>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_raw_html]JTNDaSUyMGNsYXNzJTNEJTIyaWNvLWJhcnMtY29uc3VtcHRpb24lMjIlMjBzdHlsZSUzRCUyMmZvbnQtc2l6ZSUzQTJyZW0lM0IlMjIlM0UlM0MlMkZpJTNF[\/vc_raw_html][vc_column_text]<strong>R\u00e9ponse en fr\u00e9quence avec filtrage des fuites aux hautes fr\u00e9quences.<\/strong>[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/3&Prime;][vc_raw_html]JTNDaSUyMGNsYXNzJTNEJTIyaWNvLWVsZWN0cmljLXByb3RlY3Rpb24lMjIlMjBzdHlsZSUzRCUyMmZvbnQtc2l6ZSUzQTJyZW0lM0IlMjIlM0UlM0MlMkZpJTNF[\/vc_raw_html][vc_column_text]<strong>Plus d&rsquo;immunit\u00e9 aux transistors secteur jusqu&rsquo;\u00e0 3 kA pour les impulsions 8\/20 \u03bcs<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][vc_empty_space height=\u00a0\u00bb20px\u00a0\u00bb]<\/p>\n<p>En outre, si nous ajoutons un affichage ou des communications aux performances du syst\u00e8me ultra-immunis\u00e9, nous obtenons une surveillance et un suivi de l&rsquo;\u00e9volution de la fuite dans le syst\u00e8me que nous prot\u00e9geons. Cela nous permet d&rsquo;anticiper davantage les probl\u00e8mes que les d\u00e9fauts d&rsquo;isolation et les fuites \u00e0 terre peuvent causer.<\/p>\n<p>La prochaine fois que vous allez devoir choisir la protection pour des variateurs, prenez en compte ces conseils de base. Et rappelez-vous que CIRCUTOR dispose d&rsquo;un large \u00e9ventail de solutions de protection diff\u00e9rentielle qui, avec leurs prestations d&rsquo;immunit\u00e9 et de communication, deviennent la solution id\u00e9ale pour cette application d&rsquo;usage si r\u00e9pandu.<\/p>\n<p><strong>Choisir la protection diff\u00e9rentielle appropri\u00e9e est essentiel pour assurer la fin des d\u00e9clenchements intempestifs dans vos installations. Avec notre syst\u00e8me ultra-immunis\u00e9, il est possible d&rsquo;y parvenir.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]L&rsquo;utilisation d&rsquo;un ou de plusieurs variateurs de vitesse est de plus en plus r\u00e9pandue dans de nombreux proc\u00e9d\u00e9s industriels\u00a0: des applications de base comme le pompage, aux machines pr\u00e9cises avec des op\u00e9rations robotis\u00e9es. Mais nous les utilisons aussi tous les jours\u00a0: elle est int\u00e9gr\u00e9e dans les lave-linge, les ascenseurs et les syst\u00e8mes modernes de climatisation. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":15561,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[3522],"tags":[3616,3591,3646],"class_list":["post-23822","post","type-post","status-publish","format-standard","hentry","category-articles-fr","tag-continuite-de-service","tag-economies-denergie","tag-protection-electrique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La protection diff\u00e9rentielle dans les variateurs de vitesse - CIRCUTOR<\/title>\n<meta name=\"description\" content=\"L&#039;utilisation d&#039;un ou de plusieurs variateurs de vitesse est de plus en plus r\u00e9pandue dans de nombreux proc\u00e9d\u00e9s industriels : des applications de base comme le pompage, aux machines pr\u00e9cises avec des op\u00e9rations robotis\u00e9es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La protection diff\u00e9rentielle dans les variateurs de vitesse - CIRCUTOR\" \/>\n<meta property=\"og:description\" content=\"L&#039;utilisation d&#039;un ou de plusieurs variateurs de vitesse est de plus en plus r\u00e9pandue dans de nombreux proc\u00e9d\u00e9s industriels : des applications de base comme le pompage, aux machines pr\u00e9cises avec des op\u00e9rations robotis\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/\" \/>\n<meta property=\"og:site_name\" content=\"CIRCUTOR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CIRCUTOR.ES\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T15:40:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-09T11:13:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/circutor.com\/wp-content\/uploads\/2022\/03\/Fo_Motores.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Circutor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@circutor\" \/>\n<meta name=\"twitter:site\" content=\"@circutor\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Circutor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/\"},\"author\":{\"name\":\"Circutor\",\"@id\":\"https:\\\/\\\/circutor.com\\\/#\\\/schema\\\/person\\\/06cd1bedf12980260d76632f5805f930\"},\"headline\":\"La protection diff\u00e9rentielle dans les variateurs de vitesse\",\"datePublished\":\"2022-05-25T15:40:15+00:00\",\"dateModified\":\"2022-06-09T11:13:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/\"},\"wordCount\":1420,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/circutor.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Fo_Motores.jpg\",\"keywords\":[\"Continuit\u00e9 de service\u00a0\",\"\u00c9conomies d'\u00e9nergie\u00a0\",\"Protection \u00e9lectrique\u00a0\"],\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/\",\"url\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/\",\"name\":\"La protection diff\u00e9rentielle dans les variateurs de vitesse - CIRCUTOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/circutor.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Fo_Motores.jpg\",\"datePublished\":\"2022-05-25T15:40:15+00:00\",\"dateModified\":\"2022-06-09T11:13:44+00:00\",\"description\":\"L'utilisation d'un ou de plusieurs variateurs de vitesse est de plus en plus r\u00e9pandue dans de nombreux proc\u00e9d\u00e9s industriels : des applications de base comme le pompage, aux machines pr\u00e9cises avec des op\u00e9rations robotis\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/circutor.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Fo_Motores.jpg\",\"contentUrl\":\"https:\\\/\\\/circutor.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Fo_Motores.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Arm\u00f3nicos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/circutor.com\\\/fr\\\/articles-fr\\\/la-protection-differentielle-dans-les-variateurs-de-vitesse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/circutor.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La protection diff\u00e9rentielle dans les variateurs de vitesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/circutor.com\\\/#website\",\"url\":\"https:\\\/\\\/circutor.com\\\/\",\"name\":\"CIRCUTOR\",\"description\":\"Soluciones para la eficiencia energ\u00e9tica el\u00e9ctrica\",\"publisher\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/circutor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/circutor.com\\\/#organization\",\"name\":\"Circutor\",\"url\":\"https:\\\/\\\/circutor.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/circutor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/circutor.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/CIR_LOGO_RED.png\",\"contentUrl\":\"https:\\\/\\\/circutor.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/CIR_LOGO_RED.png\",\"width\":512,\"height\":128,\"caption\":\"Circutor\"},\"image\":{\"@id\":\"https:\\\/\\\/circutor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CIRCUTOR.ES\",\"https:\\\/\\\/x.com\\\/circutor\",\"https:\\\/\\\/www.instagram.com\\\/circutor_es\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/circutor\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CIRCUTORoficial\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/circutor.com\\\/#\\\/schema\\\/person\\\/06cd1bedf12980260d76632f5805f930\",\"name\":\"Circutor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/circutor.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/usuario-logo-gris-96x96.png\",\"url\":\"https:\\\/\\\/circutor.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/usuario-logo-gris-96x96.png\",\"contentUrl\":\"https:\\\/\\\/circutor.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/usuario-logo-gris-96x96.png\",\"caption\":\"Circutor\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La protection diff\u00e9rentielle dans les variateurs de vitesse - CIRCUTOR","description":"L'utilisation d'un ou de plusieurs variateurs de vitesse est de plus en plus r\u00e9pandue dans de nombreux proc\u00e9d\u00e9s industriels : des applications de base comme le pompage, aux machines pr\u00e9cises avec des op\u00e9rations robotis\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/","og_locale":"fr_FR","og_type":"article","og_title":"La protection diff\u00e9rentielle dans les variateurs de vitesse - CIRCUTOR","og_description":"L'utilisation d'un ou de plusieurs variateurs de vitesse est de plus en plus r\u00e9pandue dans de nombreux proc\u00e9d\u00e9s industriels : des applications de base comme le pompage, aux machines pr\u00e9cises avec des op\u00e9rations robotis\u00e9es.","og_url":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/","og_site_name":"CIRCUTOR","article_publisher":"https:\/\/www.facebook.com\/CIRCUTOR.ES","article_published_time":"2022-05-25T15:40:15+00:00","article_modified_time":"2022-06-09T11:13:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/circutor.com\/wp-content\/uploads\/2022\/03\/Fo_Motores.jpg","type":"image\/jpeg"}],"author":"Circutor","twitter_card":"summary_large_image","twitter_creator":"@circutor","twitter_site":"@circutor","twitter_misc":{"\u00c9crit par":"Circutor","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/#article","isPartOf":{"@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/"},"author":{"name":"Circutor","@id":"https:\/\/circutor.com\/#\/schema\/person\/06cd1bedf12980260d76632f5805f930"},"headline":"La protection diff\u00e9rentielle dans les variateurs de vitesse","datePublished":"2022-05-25T15:40:15+00:00","dateModified":"2022-06-09T11:13:44+00:00","mainEntityOfPage":{"@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/"},"wordCount":1420,"commentCount":0,"publisher":{"@id":"https:\/\/circutor.com\/#organization"},"image":{"@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/#primaryimage"},"thumbnailUrl":"https:\/\/circutor.com\/wp-content\/uploads\/2022\/03\/Fo_Motores.jpg","keywords":["Continuit\u00e9 de service\u00a0","\u00c9conomies d'\u00e9nergie\u00a0","Protection \u00e9lectrique\u00a0"],"articleSection":["Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/","url":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/","name":"La protection diff\u00e9rentielle dans les variateurs de vitesse - CIRCUTOR","isPartOf":{"@id":"https:\/\/circutor.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/#primaryimage"},"image":{"@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/#primaryimage"},"thumbnailUrl":"https:\/\/circutor.com\/wp-content\/uploads\/2022\/03\/Fo_Motores.jpg","datePublished":"2022-05-25T15:40:15+00:00","dateModified":"2022-06-09T11:13:44+00:00","description":"L'utilisation d'un ou de plusieurs variateurs de vitesse est de plus en plus r\u00e9pandue dans de nombreux proc\u00e9d\u00e9s industriels : des applications de base comme le pompage, aux machines pr\u00e9cises avec des op\u00e9rations robotis\u00e9es.","breadcrumb":{"@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/#primaryimage","url":"https:\/\/circutor.com\/wp-content\/uploads\/2022\/03\/Fo_Motores.jpg","contentUrl":"https:\/\/circutor.com\/wp-content\/uploads\/2022\/03\/Fo_Motores.jpg","width":1920,"height":1080,"caption":"Arm\u00f3nicos"},{"@type":"BreadcrumbList","@id":"https:\/\/circutor.com\/fr\/articles-fr\/la-protection-differentielle-dans-les-variateurs-de-vitesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/circutor.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La protection diff\u00e9rentielle dans les variateurs de vitesse"}]},{"@type":"WebSite","@id":"https:\/\/circutor.com\/#website","url":"https:\/\/circutor.com\/","name":"CIRCUTOR","description":"Soluciones para la eficiencia energ\u00e9tica el\u00e9ctrica","publisher":{"@id":"https:\/\/circutor.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/circutor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/circutor.com\/#organization","name":"Circutor","url":"https:\/\/circutor.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/circutor.com\/#\/schema\/logo\/image\/","url":"https:\/\/circutor.com\/wp-content\/uploads\/2020\/09\/CIR_LOGO_RED.png","contentUrl":"https:\/\/circutor.com\/wp-content\/uploads\/2020\/09\/CIR_LOGO_RED.png","width":512,"height":128,"caption":"Circutor"},"image":{"@id":"https:\/\/circutor.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CIRCUTOR.ES","https:\/\/x.com\/circutor","https:\/\/www.instagram.com\/circutor_es","https:\/\/www.linkedin.com\/company\/circutor","https:\/\/www.youtube.com\/user\/CIRCUTORoficial"]},{"@type":"Person","@id":"https:\/\/circutor.com\/#\/schema\/person\/06cd1bedf12980260d76632f5805f930","name":"Circutor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/circutor.com\/wp-content\/uploads\/2022\/04\/usuario-logo-gris-96x96.png","url":"https:\/\/circutor.com\/wp-content\/uploads\/2022\/04\/usuario-logo-gris-96x96.png","contentUrl":"https:\/\/circutor.com\/wp-content\/uploads\/2022\/04\/usuario-logo-gris-96x96.png","caption":"Circutor"}}]}},"_links":{"self":[{"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/posts\/23822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/comments?post=23822"}],"version-history":[{"count":0,"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/posts\/23822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/media\/15561"}],"wp:attachment":[{"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/media?parent=23822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/categories?post=23822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/circutor.com\/fr\/wp-json\/wp\/v2\/tags?post=23822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}